{"id":42607,"date":"2026-02-11T00:29:11","date_gmt":"2026-02-11T00:29:11","guid":{"rendered":"https:\/\/tintafresca.net\/?p=42607"},"modified":"2026-02-11T00:37:06","modified_gmt":"2026-02-11T00:37:06","slug":"iapmei-organiza-em-leiria-e-figueira-da-foz-sessoes-de-esclarecimento-para-empresas-afetadas-pelas-tempestades","status":"publish","type":"post","link":"https:\/\/tintafresca.net\/index.php\/2026\/02\/11\/iapmei-organiza-em-leiria-e-figueira-da-foz-sessoes-de-esclarecimento-para-empresas-afetadas-pelas-tempestades\/","title":{"rendered":"IAPMEI organiza em Leiria e Figueira da Foz sess\u00f5es de esclarecimento para empresas afetadas pelas tempestades"},"content":{"rendered":"<div id=\"attachment_42440\" style=\"width: 510px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-42440\" class=\"wp-image-42440 size-full\" src=\"https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/01\/Nerlei20.jpg\" alt=\"\" width=\"500\" height=\"281\" srcset=\"https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/01\/Nerlei20.jpg 500w, https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/01\/Nerlei20-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><p id=\"caption-attachment-42440\" class=\"wp-caption-text\">Edif\u00edcio NERLEI<\/p><\/div>\n<p>O IAPMEI promove esta ter\u00e7a-feira, 11 de fevereiro, em Leiria e na Figueira da Foz, duas sess\u00f5es de esclarecimento dirigidas \u00e0s empresas das regi\u00f5es afetadas pelas recentes tempestades, no \u00e2mbito das medidas excecionais de apoio \u00e0 atividade empresarial.<\/p>\n<p>As iniciativas visam apresentar os instrumentos de apoio atualmente dispon\u00edveis, esclarecer d\u00favidas e refor\u00e7ar o contacto direto entre as entidades p\u00fablicas e o tecido empresarial local. A a\u00e7\u00e3o \u00e9 uma iniciativa do IAPMEI, em parceria com diversos organismos p\u00fablicos.<\/p>\n<p>A sess\u00e3o de Leiria decorre \u00e0s 10h00, no Audit\u00f3rio da NERLEI \u2013 Associa\u00e7\u00e3o Empresarial da Regi\u00e3o de Leiria.<\/p>\n<p>A sess\u00e3o da Figueira da Foz realiza-se \u00e0s 15h30, no Audit\u00f3rio da ACIFF \u2013 Associa\u00e7\u00e3o Comercial e Industrial da Figueira da Foz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O IAPMEI promove esta ter\u00e7a-feira, 11 de fevereiro, em Leiria e na Figueira da Foz, duas sess\u00f5es de esclarecimento dirigidas \u00e0s empresas das regi\u00f5es afetadas pelas recentes tempestades, no \u00e2mbito das medidas excecionais de apoio \u00e0 atividade empresarial. As iniciativas visam apresentar os instrumentos de apoio atualmente dispon\u00edveis, esclarecer d\u00favidas e refor\u00e7ar o contacto direto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":42441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-42607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/posts\/42607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/comments?post=42607"}],"version-history":[{"count":3,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/posts\/42607\/revisions"}],"predecessor-version":[{"id":42610,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/posts\/42607\/revisions\/42610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/media\/42441"}],"wp:attachment":[{"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/media?parent=42607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/categories?post=42607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/tags?post=42607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}