{"id":43381,"date":"2026-05-12T20:40:26","date_gmt":"2026-05-12T20:40:26","guid":{"rendered":"https:\/\/tintafresca.net\/?p=43381"},"modified":"2026-05-12T21:17:26","modified_gmt":"2026-05-12T21:17:26","slug":"doacoes-de-timor-vao-ajudar-a-reconstruir-escolas-da-marinha-grande-afetadas-pela-tempestade-kristin","status":"publish","type":"post","link":"https:\/\/tintafresca.net\/index.php\/2026\/05\/12\/doacoes-de-timor-vao-ajudar-a-reconstruir-escolas-da-marinha-grande-afetadas-pela-tempestade-kristin\/","title":{"rendered":"Doa\u00e7\u00e3o de Timor vai ajudar a reconstruir escolas da Marinha Grande afetadas pelas tempestades"},"content":{"rendered":"<div id=\"attachment_43383\" style=\"width: 510px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-43383\" class=\"wp-image-43383 size-full\" src=\"https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/05\/MG_Ministro_Fernando_Alexandre10.jpg\" alt=\"\" width=\"500\" height=\"332\" srcset=\"https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/05\/MG_Ministro_Fernando_Alexandre10.jpg 500w, https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/05\/MG_Ministro_Fernando_Alexandre10-300x199.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><p id=\"caption-attachment-43383\" class=\"wp-caption-text\">Fernando Alexandre e Paulo Vicente<\/p><\/div>\n<p>O ministro da Educa\u00e7\u00e3o, Ci\u00eancia e Inova\u00e7\u00e3o, Fernando Alexandre, reuniu com o presidente da C\u00e2mara Municipal da Marinha Grande, Paulo Vicente, esta ter\u00e7a-feira, 12 de maio, no Sal\u00e3o Nobre dos Pa\u00e7os do Concelho, no \u00e2mbito do processo de reconstru\u00e7\u00e3o das escolas afetadas pela tempestade Kristin, tratando-se da quarta desloca\u00e7\u00e3o do governante ao concelho desde a ocorr\u00eancia deste fen\u00f3meno extremo.<\/p>\n<p>A visita contou, igualmente, com a presen\u00e7a do secret\u00e1rio de Estado da Administra\u00e7\u00e3o Local e Ordenamento do Territ\u00f3rio, Silv\u00e9rio Regalado, bem como da vice-presidente da CCDR Centro, Cristina Oliveira; da vereadora da Educa\u00e7\u00e3o, Carla Santana; e de representantes da Constru\u00e7\u00e3o P\u00fablica e das entidades envolvidas.<\/p>\n<p>A reuni\u00e3o constituiu um momento de articula\u00e7\u00e3o entre o Governo e o Munic\u00edpio, permitindo alinhar estrat\u00e9gias e acelerar a concretiza\u00e7\u00e3o de solu\u00e7\u00f5es para a reconstru\u00e7\u00e3o e moderniza\u00e7\u00e3o da rede escolar, com foco na seguran\u00e7a, resili\u00eancia e resposta \u00e0s necessidades da comunidade educativa.<\/p>\n<p>Durante o encontro foram analisados os projetos de reabilita\u00e7\u00e3o da rede escolar, que dever\u00e3o ser financiados pelo Banco Europeu de Investimento (BEI) e enquadrados nas orienta\u00e7\u00f5es do PTRR, com o objetivo de refor\u00e7ar a resili\u00eancia das infraestruturas perante fen\u00f3menos clim\u00e1ticos extremos.<\/p>\n<p>O ministro da Educa\u00e7\u00e3o destacou a necessidade de avan\u00e7ar com as interven\u00e7\u00f5es, sublinhando que \u201c\u00e9 fundamental come\u00e7armos rapidamente a reconstru\u00e7\u00e3o das escolas\u201d e que \u201cas interven\u00e7\u00f5es ser\u00e3o financiadas pelo PTRR, garantindo as condi\u00e7\u00f5es necess\u00e1rias para avan\u00e7ar com celeridade\u201d.<\/p>\n<div id=\"attachment_43384\" style=\"width: 510px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-43384\" class=\"wp-image-43384 size-full\" src=\"https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/05\/MG_Ministro_Fernando_Alexandre20.jpg\" alt=\"\" width=\"500\" height=\"332\" srcset=\"https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/05\/MG_Ministro_Fernando_Alexandre20.jpg 500w, https:\/\/tintafresca.net\/wp-content\/uploads\/2026\/05\/MG_Ministro_Fernando_Alexandre20-300x199.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><p id=\"caption-attachment-43384\" class=\"wp-caption-text\">Reuni\u00e3o decorreu nos Pa\u00e7os do Concelho<\/p><\/div>\n<p>Fernando Alexandre salientou ainda que \u201cpretendemos que esta reconstru\u00e7\u00e3o seja feita com base num novo modelo, mais resiliente, olhando para o futuro e fazendo diferente\u201d, acrescentando que \u201calgumas destas escolas devem ser preparadas como locais de abrigo e ref\u00fagio das popula\u00e7\u00f5es, com conectividade e condi\u00e7\u00f5es adequadas para situa\u00e7\u00f5es de emerg\u00eancia\u201d.<\/p>\n<p>No \u00e2mbito do financiamento, o ministro recordou que \u201co Governo de Timor-Leste doou 5 milh\u00f5es de d\u00f3lares, verba que o Governo portugu\u00eas decidiu investir na recupera\u00e7\u00e3o das escolas nos concelhos de Leiria e da Marinha Grande, em fun\u00e7\u00e3o do n\u00famero de alunos\u201d, especificando que \u201ccerca de 1,3 milh\u00f5es ser\u00e3o aplicados na Marinha Grande, sendo o restante montante destinado a Leiria\u201d.<\/p>\n<p>O presidente da C\u00e2mara Municipal da Marinha Grande, Paulo Vicente, evidenciou a estrat\u00e9gia do Munic\u00edpio para reorganiza\u00e7\u00e3o da rede escolar, sobretudo na freguesia de Vieira de Leiria, onde se registaram mais danos, afirmando que \u201cpretendemos transformar a Escola Padre Franklin num verdadeiro centro escolar, integrando 12 turmas do 1.\u00ba ciclo e quatro da educa\u00e7\u00e3o pr\u00e9-escolar, promovendo solu\u00e7\u00f5es mais eficientes e resilientes\u201d.<\/p>\n<p>Paulo Vicente destacou ainda os desafios em curso, referindo que \u201cexistem pequenas escolas que exigem investimentos muito elevados e queremos avan\u00e7ar para solu\u00e7\u00f5es estruturais mais eficazes\u201d.<\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 Fonte: GCI|CMMG<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro da Educa\u00e7\u00e3o, Ci\u00eancia e Inova\u00e7\u00e3o, Fernando Alexandre, reuniu com o presidente da C\u00e2mara Municipal da Marinha Grande, Paulo Vicente, esta ter\u00e7a-feira, 12 de maio, no Sal\u00e3o Nobre dos Pa\u00e7os do Concelho, no \u00e2mbito do processo de reconstru\u00e7\u00e3o das escolas afetadas pela tempestade Kristin, tratando-se da quarta desloca\u00e7\u00e3o do governante ao concelho desde a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":43385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-43381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/posts\/43381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/comments?post=43381"}],"version-history":[{"count":5,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/posts\/43381\/revisions"}],"predecessor-version":[{"id":43389,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/posts\/43381\/revisions\/43389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/media\/43385"}],"wp:attachment":[{"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/media?parent=43381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/categories?post=43381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tintafresca.net\/index.php\/wp-json\/wp\/v2\/tags?post=43381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}